{"id":9444,"date":"2021-02-25T15:02:39","date_gmt":"2021-02-25T14:02:39","guid":{"rendered":"https:\/\/niroflex.de\/faq\/"},"modified":"2025-11-19T17:19:41","modified_gmt":"2025-11-19T16:19:41","slug":"es-niroflex-faq","status":"publish","type":"page","link":"https:\/\/niroflex.de\/es\/es-niroflex-faq\/","title":{"rendered":"FAQ \u2013 Preguntas y Respuestas"},"content":{"rendered":"<div class=\"wpb-content-wrapper\">[vc_row thb_full_width=\u00bbtrue\u00bb parallax=\u00bbcontent-moving\u00bb thb_divider_position=\u00bbbottom\u00bb css=\u00bb.vc_custom_1556805173564{background-color: #000000 !important;background-position: center;background-repeat: no-repeat;background-size:contain !important;}\u00bb][vc_column][vc_empty_space height=\u00bb110px\u00bb][\/vc_column][\/vc_row][vc_row thb_divider_position=\u00bbbottom\u00bb][vc_column][vc_empty_space height=\u00bb80px\u00bb][vc_icon type=\u00bbtypicons\u00bb icon_typicons=\u00bbtypcn typcn-messages\u00bb color=\u00bbcustom\u00bb size=\u00bbxl\u00bb css=\u00bb.vc_custom_1614164153090{padding-bottom: -20px !important;}\u00bb custom_color=\u00bb#dd3333&#8243;][vc_column_text css=\u00bb\u00bb]\n<h1 style=\"font-size: 2em;\">FAQ \u2013 <span class=\"s1\">preguntas frecuentes<\/span><\/h1>\n<p>En \u0109i tiu sekcio, vi trovos la plej gravajn informojn pri niaj produktoj, ilia apliko kaj prizorgado. La Oftaj Demandoj helpos vin rapide trovi respondojn al la plej ofte farataj demandoj de niaj klientoj.[\/vc_column_text][vc_empty_space height=\u00bb30px\u00bb][\/vc_column][\/vc_row][vc_row thb_divider_position=\u00bbbottom\u00bb][vc_column width=\u00bb1\/2&#8243;][vc_column_text css=\u00bb\u00bb]\n<h2>Guantes de malla, delantales, boleros<\/h2>\n[\/vc_column_text][vc_separator color=\u00bbcustom\u00bb accent_color=\u00bb#dd3333&#8243;][vc_toggle title=\u00bbLimpieza y mantenimiento\u00bb color=\u00bbjuicy_pink\u00bb size=\u00bblg\u00bb custom_font_container=\u00bbtag:h2|font_size:18|text_align:left|line_height:1&#8243; custom_use_theme_fonts=\u00bbyes\u00bb css=\u00bb\u00bb use_custom_heading=\u00bbtrue\u00bb]Los productos hechos de malla anular deben limpiarse inmediatamente despu\u00e9s de su uso con agua tibia, aproximadamente a 50 \u00b0C, a\u00f1adiendo agentes de limpieza com\u00fanmente utilizados en la industria c\u00e1rnica y alimentaria, mediante un cepillado vigoroso. Tambi\u00e9n se consigue una muy buena limpieza si los guantes o delantales se lavan en una lavadora normal o de uso habitual. Una vez secado el producto, se debe rociar con un desinfectante de uso com\u00fan en la industria alimentaria (dejar actuar unos minutos). Despu\u00e9s de la limpieza, guarde los productos en un lugar seco, fresco y bien ventilado. Es importante asegurarse de que solo se utilicen desinfectantes de uso com\u00fan en la industria alimentaria. Los desinfectantes con un contenido excesivo de cloro y \u00e1cido pueden da\u00f1ar los productos.[\/vc_toggle][vc_toggle title=\u00bbMano izquierda &#8211; mano derecha\u00bb color=\u00bbjuicy_pink\u00bb size=\u00bblg\u00bb custom_font_container=\u00bbtag:h2|font_size:18|text_align:left|line_height:1&#8243; custom_use_theme_fonts=\u00bbyes\u00bb css=\u00bb\u00bb use_custom_heading=\u00bbtrue\u00bb]Mano izquierda \u2013 mano derecha<img decoding=\"async\" class=\"alignnone size-full wp-image-9495 lazyload\" src=\"data:image\/gif;base64,R0lGODlhAQABAAAAACH5BAEKAAEALAAAAAABAAEAAAICTAEAOw==\" data-src=\"https:\/\/niroflex.de\/wp-content\/uploads\/2021\/02\/LCR_es.jpg\" alt=\"\" width=\"187\" height=\"55\" data-sizes=\"auto\" data-srcset=\"https:\/\/niroflex.de\/wp-content\/uploads\/2021\/02\/LCR_es.jpg 187w, https:\/\/niroflex.de\/wp-content\/uploads\/2021\/02\/LCR_es-20x6.jpg 20w\" sizes=\"(max-width: 187px) 100vw, 187px\" \/>[\/vc_toggle][vc_toggle title=\u00bbInstrucciones para determinar la talla correcta de guantes\u00bb color=\u00bbjuicy_pink\u00bb size=\u00bblg\u00bb custom_font_container=\u00bbtag:h2|font_size:18|text_align:left|line_height:1&#8243; custom_use_theme_fonts=\u00bbyes\u00bb css=\u00bb\u00bb use_custom_heading=\u00bbtrue\u00bb]Los guantes no deben usarse demasiado apretados, ya que esto limita su flexibilidad y las propiedades de uso. Recomendamos a\u00f1adir 5 mm a la circunferencia para un ajuste c\u00f3modo. Si se usa un guante de algod\u00f3n o un guante interior debajo del guante de malla anular, es necesario a\u00f1adir otros 3 mm a la circunferencia.<\/p>\n<p><img decoding=\"async\" class=\"alignnone size-full wp-image-9527 lazyload\" src=\"data:image\/gif;base64,R0lGODlhAQABAAAAACH5BAEKAAEALAAAAAABAAEAAAICTAEAOw==\" data-src=\"https:\/\/niroflex.de\/wp-content\/uploads\/2021\/03\/ringgeflecht-es.jpg\" alt=\"\" width=\"1147\" height=\"298\" data-sizes=\"auto\" data-srcset=\"https:\/\/niroflex.de\/wp-content\/uploads\/2021\/03\/ringgeflecht-es.jpg 1147w, https:\/\/niroflex.de\/wp-content\/uploads\/2021\/03\/ringgeflecht-es-1024x266.jpg 1024w, https:\/\/niroflex.de\/wp-content\/uploads\/2021\/03\/ringgeflecht-es-768x200.jpg 768w, https:\/\/niroflex.de\/wp-content\/uploads\/2021\/03\/ringgeflecht-es-640x166.jpg 640w, https:\/\/niroflex.de\/wp-content\/uploads\/2021\/03\/ringgeflecht-es-320x83.jpg 320w, https:\/\/niroflex.de\/wp-content\/uploads\/2021\/03\/ringgeflecht-es-20x5.jpg 20w\" sizes=\"(max-width: 1147px) 100vw, 1147px\" \/>[\/vc_toggle][vc_toggle title=\u00bbPesos\/Tallas: Boleros\u00bb color=\u00bbjuicy_pink\u00bb size=\u00bblg\u00bb custom_font_container=\u00bbtag:h2|font_size:18|text_align:left|line_height:1&#8243; custom_use_theme_fonts=\u00bbyes\u00bb use_custom_heading=\u00bbtrue\u00bb]\n<p id=\"tw-target-text\" class=\"tw-data-text tw-text-large XcVN5d tw-ta\" dir=\"ltr\" data-placeholder=\"\u00dcbersetzung\"><span lang=\"es\">Consulte la informaci\u00f3n en la <a href=\"\/es\/portfolio\/niroflex-boleros\/\">tabla de tallas en la p\u00e1gina del producto<\/a>.<\/span><\/p>\n[\/vc_toggle][vc_toggle title=\u00bbPesos\/Tallas: Delantales\u00bb color=\u00bbjuicy_pink\u00bb size=\u00bblg\u00bb custom_font_container=\u00bbtag:h2|font_size:18|text_align:left|line_height:1&#8243; custom_use_theme_fonts=\u00bbyes\u00bb use_custom_heading=\u00bbtrue\u00bb]<span lang=\"es\">Consulte la informaci\u00f3n en la <a href=\"\/es\/portfolio\/niroflex-schuerzen\/\">tabla de tallas en la p\u00e1gina del producto<\/a>.<\/span>[\/vc_toggle][vc_toggle title=\u00bbReparaciones\u00bb color=\u00bbjuicy_pink\u00bb size=\u00bblg\u00bb custom_font_container=\u00bbtag:h2|font_size:18|text_align:left|line_height:1&#8243; custom_use_theme_fonts=\u00bbyes\u00bb use_custom_heading=\u00bbtrue\u00bb]Los delantales y guantes de protecci\u00f3n anticorte solo pueden utilizarse siguiendo las indicaciones del fabricante. Solo de esta forma los productos cumplen con los requisitos nacionales y europeos. Para el trabajo solo se pueden utilizar productos que est\u00e9n en perfectas condiciones. Las reparaciones necesarias pueden realizarse con repuestos originales. Solo en ese caso se garantiza una reparaci\u00f3n profesional. Gracias al servicio de reparaci\u00f3n original de niroflex, le ayudamos de manera profesional y sin papeleos con los problemas relacionados con los productos de malla anular que cumplen con la normativa CE.[\/vc_toggle][vc_toggle title=\u00bbC\u00f3digo de colores\u00bb color=\u00bbjuicy_pink\u00bb size=\u00bblg\u00bb custom_font_container=\u00bbtag:h2|font_size:18|text_align:left|line_height:1&#8243; custom_use_theme_fonts=\u00bbyes\u00bb use_custom_heading=\u00bbtrue\u00bb]marr\u00f3n = XXS, verde = XS, blanco = S, rojo = M, azul = L, naranja = XL, oliva = XXL[\/vc_toggle][vc_toggle title=\u00bbSocio comercial a nivel nacional y en el extranjero\u00bb color=\u00bbjuicy_pink\u00bb size=\u00bblg\u00bb custom_font_container=\u00bbtag:h2|font_size:18|text_align:left|line_height:1&#8243; custom_use_theme_fonts=\u00bbyes\u00bb use_custom_heading=\u00bbtrue\u00bb]Internacional: <a href=\"https:\/\/niroflex.de\/es\/distribucion\/\">Distribuci\u00f3n<\/a><br \/>\nNacional = socio comercial regional[\/vc_toggle][vc_toggle title=\u00bbMOQ\u00bb color=\u00bbjuicy_pink\u00bb size=\u00bblg\u00bb custom_font_container=\u00bbtag:h2|font_size:18|text_align:left|line_height:1&#8243; custom_use_theme_fonts=\u00bbyes\u00bb use_custom_heading=\u00bbtrue\u00bb]bajo pedido[\/vc_toggle][vc_toggle title=\u00bbCertificaci\u00f3n ISO\u00bb color=\u00bbjuicy_pink\u00bb size=\u00bblg\u00bb custom_font_container=\u00bbtag:h2|font_size:18|text_align:left|line_height:1&#8243; custom_use_theme_fonts=\u00bbyes\u00bb use_custom_heading=\u00bbtrue\u00bb]ISO 9001[\/vc_toggle][vc_toggle title=\u00bbCuchillos\/sierras el\u00e9ctricas\u00bb color=\u00bbjuicy_pink\u00bb size=\u00bblg\u00bb custom_font_container=\u00bbtag:h2|font_size:18|text_align:left|line_height:1&#8243; custom_use_theme_fonts=\u00bbyes\u00bb use_custom_heading=\u00bbtrue\u00bb]Sin excepci\u00f3n: easyfit puede utilizarse de forma limitada[\/vc_toggle][vc_toggle title=\u00bbDimensiones de las anillas de los delantales\/boleros\u00bb color=\u00bbjuicy_pink\u00bb size=\u00bblg\u00bb custom_font_container=\u00bbtag:h2|font_size:18|text_align:left|line_height:1&#8243; custom_use_theme_fonts=\u00bbyes\u00bb use_custom_heading=\u00bbtrue\u00bb]Cuando se utilizan cuchillos extremadamente afilados, se recomienda \u00d8 4,2 mm. De lo contrario \u00d8 7,0 mm[\/vc_toggle][vc_toggle title=\u00bbPlazo de entrega\u00bb color=\u00bbjuicy_pink\u00bb size=\u00bblg\u00bb custom_font_container=\u00bbtag:h2|font_size:18|text_align:left|line_height:1&#8243; custom_use_theme_fonts=\u00bbyes\u00bb use_custom_heading=\u00bbtrue\u00bb]La mayor\u00eda de los productos est\u00e1n disponibles en stock. Los pedidos de nuestra gama est\u00e1ndar salen de nuestro centro log\u00edstico el mismo d\u00eda.[\/vc_toggle][vc_toggle title=\u00bbProducci\u00f3n especial\u00bb color=\u00bbjuicy_pink\u00bb size=\u00bblg\u00bb custom_font_container=\u00bbtag:h2|font_size:18|text_align:left|line_height:1&#8243; custom_use_theme_fonts=\u00bbyes\u00bb use_custom_heading=\u00bbtrue\u00bb]Es posible personalizar los productos en funci\u00f3n del usuario y de la aplicaci\u00f3n. Desarrollamos ideas y productos junto con nuestros clientes y creamos soluciones a medida, orientadas a la aplicaci\u00f3n hasta el m\u00e1s m\u00ednimo detalle.[\/vc_toggle][vc_empty_space height=\u00bb30px\u00bb][\/vc_column][vc_column width=\u00bb1\/2&#8243;][vc_column_text css=\u00bb\u00bb]\n<h2>Guantes de Protecci\u00f3n<\/h2>\n[\/vc_column_text][vc_separator color=\u00bbcustom\u00bb accent_color=\u00bb#dd3333&#8243;][vc_toggle title=\u00bbLimpieza y mantenimiento\u00bb color=\u00bbjuicy_pink\u00bb size=\u00bblg\u00bb custom_font_container=\u00bbtag:h2|font_size:18|text_align:left|line_height:1%2C5&#8243; custom_use_theme_fonts=\u00bbyes\u00bb css=\u00bb\u00bb use_custom_heading=\u00bbtrue\u00bb]\n<p class=\"p1\">Instrucciones de lavado y mantenimiento.<span class=\"s1\"><br \/>\n<\/span>Lave los guantes con el programa de lavado normal sin superar los 85 \u00b0C. El centrifugado reduce el tiempo de secado. Cuando se utiliza una secadora, no se debe exceder la temperatura (m\u00e1x. 70 \u00b0C) y el tiempo de secado (m\u00e1x. 10 minutos).<span class=\"s1\"><br \/>\n<\/span> Los guantes deben almacenarse en un lugar seco.<\/p>\n[\/vc_toggle][vc_toggle title=\u00bbMano izquierda \u2013 mano derecha\u00bb color=\u00bbjuicy_pink\u00bb size=\u00bblg\u00bb custom_font_container=\u00bbtag:h2|font_size:18|text_align:left|line_height:1&#8243; custom_use_theme_fonts=\u00bbyes\u00bb css=\u00bb\u00bb use_custom_heading=\u00bbtrue\u00bb]<img decoding=\"async\" class=\"alignnone size-full wp-image-9495 lazyload\" src=\"data:image\/gif;base64,R0lGODlhAQABAAAAACH5BAEKAAEALAAAAAABAAEAAAICTAEAOw==\" data-src=\"https:\/\/niroflex.de\/wp-content\/uploads\/2021\/02\/LCR_es.jpg\" alt=\"\" width=\"187\" height=\"55\" data-sizes=\"auto\" data-srcset=\"https:\/\/niroflex.de\/wp-content\/uploads\/2021\/02\/LCR_es.jpg 187w, https:\/\/niroflex.de\/wp-content\/uploads\/2021\/02\/LCR_es-20x6.jpg 20w\" sizes=\"(max-width: 187px) 100vw, 187px\" \/>[\/vc_toggle][vc_toggle title=\u00bbInstrucciones para determinar la talla correcta de guantes\u00bb color=\u00bbjuicy_pink\u00bb size=\u00bblg\u00bb custom_font_container=\u00bbtag:h2|font_size:18|text_align:left|line_height:1&#8243; custom_use_theme_fonts=\u00bbyes\u00bb css=\u00bb\u00bb use_custom_heading=\u00bbtrue\u00bb]<img decoding=\"async\" class=\"alignnone wp-image-9335 size-full lazyload\" src=\"data:image\/gif;base64,R0lGODlhAQABAAAAACH5BAEKAAEALAAAAAABAAEAAAICTAEAOw==\" data-src=\"https:\/\/niroflex.de\/wp-content\/uploads\/2021\/02\/cut-protection-measurement.png\" alt=\"\" width=\"561\" height=\"226\" data-sizes=\"auto\" data-srcset=\"https:\/\/niroflex.de\/wp-content\/uploads\/2021\/02\/cut-protection-measurement.png 561w, https:\/\/niroflex.de\/wp-content\/uploads\/2021\/02\/cut-protection-measurement-320x129.png 320w, https:\/\/niroflex.de\/wp-content\/uploads\/2021\/02\/cut-protection-measurement-20x9.png 20w\" sizes=\"(max-width: 561px) 100vw, 561px\" \/>[\/vc_toggle][vc_toggle title=\u00bbQu\u00e9 significa la protecci\u00f3n contra cortes?\u00bb color=\u00bbjuicy_pink\u00bb size=\u00bblg\u00bb custom_font_container=\u00bbtag:h2|font_size:18|text_align:left|line_height:1&#8243; custom_use_theme_fonts=\u00bbyes\u00bb css=\u00bb\u00bb use_custom_heading=\u00bbtrue\u00bb]\n<p class=\"p1\">Los guantes resistentes a cortes Niroflex ofrecen una alta resistencia a los cortes y la abrasi\u00f3n, pero no cuentan con protecci\u00f3n contra perforaciones. Los guantes no deben usarse cerca de hojas el\u00e9ctricas, cuchillos, sierras o herramientas similares.<\/p>\n[\/vc_toggle][vc_toggle title=\u00bbTolerancia cut\u00e1nea\u00bb color=\u00bbjuicy_pink\u00bb size=\u00bblg\u00bb custom_font_container=\u00bbtag:h2|font_size:18|text_align:left|line_height:1&#8243; custom_use_theme_fonts=\u00bbyes\u00bb use_custom_heading=\u00bbtrue\u00bb]\n<p class=\"p1\">En general, los guantes no da\u00f1an la piel y no deber\u00edan provocar alergias si se utilizan con un detergente de uso est\u00e1ndar.<\/p>\n[\/vc_toggle][vc_toggle title=\u00bbCiclos de lavado\u00bb color=\u00bbjuicy_pink\u00bb size=\u00bblg\u00bb custom_font_container=\u00bbtag:h2|font_size:18|text_align:left|line_height:1&#8243; custom_use_theme_fonts=\u00bbyes\u00bb use_custom_heading=\u00bbtrue\u00bb]\n<p class=\"p1\">Durante el trabajo solo se pueden utilizar guantes Niroflex BlueCut que est\u00e9n en perfectas condiciones. El comprador o el usuario son responsables del correcto uso de los guantes. El fabricante o el vendedor no asumen ninguna responsabilidad ni garant\u00eda. No se garantiza que los niveles de rendimiento especificados se mantengan despu\u00e9s de m\u00e1s de 20 ciclos de lavado.<\/p>\n[\/vc_toggle][vc_toggle title=\u00bbC\u00f3digo de colores\u00bb color=\u00bbjuicy_pink\u00bb size=\u00bblg\u00bb custom_font_container=\u00bbtag:h2|font_size:18|text_align:left|line_height:1&#8243; custom_use_theme_fonts=\u00bbyes\u00bb use_custom_heading=\u00bbtrue\u00bb]\n<p class=\"p1\">marr\u00f3n = XXS, verde = XS, blanco = S, rojo = M, azul = L, naranja = XL, oliva = XXL<\/p>\n[\/vc_toggle][vc_toggle title=\u00bbSocio comercial a nivel nacional y en el extranjero\u00bb color=\u00bbjuicy_pink\u00bb size=\u00bblg\u00bb custom_font_container=\u00bbtag:h2|font_size:18|text_align:left|line_height:1%2C5&#8243; custom_use_theme_fonts=\u00bbyes\u00bb use_custom_heading=\u00bbtrue\u00bb]Internacional: <a href=\"https:\/\/niroflex.de\/es\/distribucion\/\">Distribuci\u00f3n<\/a><br \/>\nNacional = socio comercial regional[\/vc_toggle][vc_toggle title=\u00bbMOQ\u00bb color=\u00bbjuicy_pink\u00bb size=\u00bblg\u00bb custom_font_container=\u00bbtag:h2|font_size:18|text_align:left|line_height:1&#8243; custom_use_theme_fonts=\u00bbyes\u00bb use_custom_heading=\u00bbtrue\u00bb]\n<p class=\"p1\">10 piezas por talla<\/p>\n[\/vc_toggle][vc_toggle title=\u00bbCuchillos\/sierras el\u00e9ctricas\u00bb color=\u00bbjuicy_pink\u00bb size=\u00bblg\u00bb custom_font_container=\u00bbtag:h2|font_size:18|text_align:left|line_height:1&#8243; custom_use_theme_fonts=\u00bbyes\u00bb use_custom_heading=\u00bbtrue\u00bb]\n<p class=\"p2\">No.<\/p>\n[\/vc_toggle][vc_toggle title=\u00bbEliminaci\u00f3n de residuos\u00bb color=\u00bbjuicy_pink\u00bb size=\u00bblg\u00bb custom_font_container=\u00bbtag:h2|font_size:18|text_align:left|line_height:1&#8243; custom_use_theme_fonts=\u00bbyes\u00bb use_custom_heading=\u00bbtrue\u00bb]\n<p class=\"p1\">Los guantes usados deben eliminarse de acuerdo con las normas de eliminaci\u00f3n de residuos contaminantes y las regulaciones locales. Los guantes que no se hayan usado pueden eliminarse con la basura dom\u00e9stica.<\/p>\n[\/vc_toggle][vc_toggle title=\u00bbPlazo de entrega\u00bb color=\u00bbjuicy_pink\u00bb size=\u00bblg\u00bb custom_font_container=\u00bbtag:h2|font_size:18|text_align:left|line_height:1&#8243; custom_use_theme_fonts=\u00bbyes\u00bb use_custom_heading=\u00bbtrue\u00bb]\n<p class=\"p1\">La mayor\u00eda de los productos est\u00e1n disponibles en stock.<\/p>\n[\/vc_toggle][vc_toggle title=\u00bbM\u00e9todo de prueba para determinar la resistencia al corte.\u00bb color=\u00bbjuicy_pink\u00bb size=\u00bblg\u00bb custom_font_container=\u00bbtag:h2|font_size:18|text_align:left|line_height:1%2C5&#8243; custom_use_theme_fonts=\u00bbyes\u00bb use_custom_heading=\u00bbtrue\u00bb]\n<p class=\"p1\">El \u00abCoupe Test\u00bb (EN 388:2003) sigue formando parte de la norma EN 388:2016. Como prueba de corte adicional, el m\u00e9todo de prueba de la ISO 13997 se integr\u00f3 en la EN 388 actual. Esta prueba es m\u00e1s relevante que el anterior \u00abCoupe Test\u00bb, ya que la fuerza real medida durante el corte se proporciona en Newtons (N). Las clases de protecci\u00f3n contra cortes se clasifican con una codificaci\u00f3n entre las letras A-F, donde A (2N) representa el nivel de rendimiento m\u00e1s bajo y F (30N) el m\u00e1s alto.<\/p>\n[\/vc_toggle][vc_toggle title=\u00bbSoluciones de aplicaci\u00f3n\u00bb color=\u00bbjuicy_pink\u00bb size=\u00bblg\u00bb custom_font_container=\u00bbtag:h2|font_size:18|text_align:left|line_height:1&#8243; custom_use_theme_fonts=\u00bbyes\u00bb use_custom_heading=\u00bbtrue\u00bb]\n<p class=\"p1\">Nos basamos en 100 a\u00f1os de experiencia t\u00e9cnica relacionada con \u00e1reas de trabajo cr\u00edticas para ayudar a nuestros distribuidores y a sus clientes a elegir el producto adecuado para sus necesidades. Siempre estamos disponibles para responder a sus preguntas.<\/p>\n[\/vc_toggle][vc_toggle title=\u00bbReacciones al\u00e9rgicas\u00bb color=\u00bbjuicy_pink\u00bb size=\u00bblg\u00bb custom_font_container=\u00bbtag:h2|font_size:18|text_align:left|line_height:1&#8243; custom_use_theme_fonts=\u00bbyes\u00bb use_custom_heading=\u00bbtrue\u00bb]\n<p class=\"p1\">Una reacci\u00f3n al\u00e9rgica causada por los guantes es la reacci\u00f3n a las prote\u00ednas de nitrilo o a los aditivos utilizados en la fabricaci\u00f3n de los guantes. Si bien la mayor\u00eda de las alergias generalmente presentan s\u00edntomas leves, un porcentaje muy peque\u00f1o puede provocar reacciones graves.<\/p>\n[\/vc_toggle][vc_toggle title=\u00bbGuantes con pu\u00f1o\u00bb color=\u00bbjuicy_pink\u00bb size=\u00bblg\u00bb custom_font_container=\u00bbtag:h2|font_size:18|text_align:left|line_height:1&#8243; custom_use_theme_fonts=\u00bbyes\u00bb css=\u00bb\u00bb use_custom_heading=\u00bbtrue\u00bb]\n<p class=\"p1\">Recomendamos un guante con un guantelete de cierta longitud (aprox. 40,5 cm) si quiere estar protegido hasta el codo. Tambi\u00e9n es adecuado para colocar sobre el protector de brazo.<\/p>\n[\/vc_toggle][vc_toggle title=\u00bbCu\u00e1ndo y d\u00f3nde debo usar guantes resistentes a cortes?\u00bb color=\u00bbjuicy_pink\u00bb size=\u00bblg\u00bb custom_font_container=\u00bbtag:h2|font_size:18|text_align:left|line_height:1%2C5&#8243; custom_use_theme_fonts=\u00bbyes\u00bb css=\u00bb\u00bb use_custom_heading=\u00bbtrue\u00bb]\n<p class=\"p1\">Cuando use cuchillos manuales, use guantes resistentes a cortes en la mano que sostiene el material cortado y en la mano que sostiene el cuchillo.<\/p>\n[\/vc_toggle][vc_toggle title=\u00bbLos guantes son adecuados para la industria alimentaria?\u00bb color=\u00bbjuicy_pink\u00bb size=\u00bblg\u00bb custom_font_container=\u00bbtag:h2|font_size:18|text_align:left|line_height:1%2C5&#8243; custom_use_theme_fonts=\u00bbyes\u00bb css=\u00bb\u00bb use_custom_heading=\u00bbtrue\u00bb]\n<p class=\"p1\">Todos nuestros guantes son adecuados para su uso en el procesamiento o fabricaci\u00f3n de alimentos.<\/p>\n[\/vc_toggle][vc_toggle title=\u00bbQu\u00e9 recoge la norma DIN EN 388:2003?\u00bb color=\u00bbjuicy_pink\u00bb size=\u00bblg\u00bb custom_font_container=\u00bbtag:h2|font_size:18|text_align:left|line_height:1%2C5&#8243; custom_use_theme_fonts=\u00bbyes\u00bb css=\u00bb\u00bb use_custom_heading=\u00bbtrue\u00bb]\n<p class=\"p1\">La norma europea DIN EN 388:2003 describe los requisitos, m\u00e9todos de prueba y el etiquetado de los guantes de protecci\u00f3n con respecto a las cargas f\u00edsicas y mec\u00e1nicas durante la realizaci\u00f3n de trabajos. Esta norma se aplica junto con la norma b\u00e1sica DIN EN 420. Los riesgos y cargas mec\u00e1nicas y sus m\u00e9todos de ensayo se definen en la norma DIN EN 388:2003 de la siguiente forma: resistencia a la abrasi\u00f3n; resistencia al corte; resistencia a los desgarros; resistencia a la perforaci\u00f3n.<\/p>\n[\/vc_toggle][vc_toggle title=\u00bbQu\u00e9 significa el t\u00e9rmino \u00abresistencia a la abrasi\u00f3n\u00bb?\u00bb color=\u00bbjuicy_pink\u00bb size=\u00bblg\u00bb custom_font_container=\u00bbtag:h2|font_size:18|text_align:left|line_height:1%2C5&#8243; custom_use_theme_fonts=\u00bbyes\u00bb css=\u00bb\u00bb use_custom_heading=\u00bbtrue\u00bb]\n<p class=\"p1\">La resistencia a la abrasi\u00f3n se determina como el n\u00famero de ciclos necesarios para que se produzca la rotura. La rotura es la condici\u00f3n en la que la muestra de prueba se desgasta tanto que aparece un agujero.<\/p>\n[\/vc_toggle][vc_toggle title=\u00bbQu\u00e9 significa el t\u00e9rmino \u00abresistencia al corte\u00bb?\u00bb color=\u00bbjuicy_pink\u00bb size=\u00bblg\u00bb custom_font_container=\u00bbtag:h2|font_size:18|text_align:left|line_height:1%2C5&#8243; custom_use_theme_fonts=\u00bbyes\u00bb css=\u00bb\u00bb use_custom_heading=\u00bbtrue\u00bb]\n<p class=\"p1\">El valor de resistencia al corte se basa en el n\u00famero de ciclos de prueba necesarios para cortar el guante de prueba con una carga fija (5N) y a una velocidad constante.<\/p>\n[\/vc_toggle][vc_toggle title=\u00bbQu\u00e9 significa el t\u00e9rmino \u00abresistencia a los desgarros\u00bb?\u00bb color=\u00bbjuicy_pink\u00bb size=\u00bblg\u00bb custom_font_container=\u00bbtag:h2|font_size:18|text_align:left|line_height:1%2C5&#8243; custom_use_theme_fonts=\u00bbyes\u00bb css=\u00bb\u00bb use_custom_heading=\u00bbtrue\u00bb]\n<p class=\"p1\">La resistencia a los desgarros se define como la fuerza que se requiere para abrir una grieta en una muestra de prueba rectangular en la mitad de la longitud de la muestra de prueba.<\/p>\n[\/vc_toggle][vc_toggle title=\u00bbQu\u00e9 significa el t\u00e9rmino \u00abresistencia a la perforaci\u00f3n\u00bb?\u00bb color=\u00bbjuicy_pink\u00bb size=\u00bblg\u00bb custom_font_container=\u00bbtag:h2|font_size:18|text_align:left|line_height:1%2C5&#8243; custom_use_theme_fonts=\u00bbyes\u00bb css=\u00bb\u00bb use_custom_heading=\u00bbtrue\u00bb]\n<p class=\"p1\">La fuerza de perforaci\u00f3n se define como la fuerza que se requiere para perforar una muestra de prueba montada sobre un dispositivo de sujeci\u00f3n con la ayuda de un pasador de acero de unas dimensiones concretas. No debe confundirse con la perforaci\u00f3n realizada con puntas finas o agujas.<\/p>\n[\/vc_toggle][vc_toggle title=\u00bbEtiquetado\u00bb color=\u00bbjuicy_pink\u00bb size=\u00bblg\u00bb custom_font_container=\u00bbtag:h2|font_size:18|text_align:left|line_height:1&#8243; custom_use_theme_fonts=\u00bbyes\u00bb use_custom_heading=\u00bbtrue\u00bb]\n<p class=\"p1\">La funci\u00f3n de protecci\u00f3n contra lesiones mec\u00e1nicas se muestra con un pictograma y cinco d\u00edgitos. Indican los respectivos niveles de rendimiento.<\/p>\n<p><img decoding=\"async\" class=\"alignnone size-full wp-image-9341 lazyload\" src=\"data:image\/gif;base64,R0lGODlhAQABAAAAACH5BAEKAAEALAAAAAABAAEAAAICTAEAOw==\" data-src=\"https:\/\/niroflex.de\/wp-content\/uploads\/2021\/02\/EN388.png\" alt=\"\" width=\"252\" height=\"218\" data-sizes=\"auto\" data-srcset=\"https:\/\/niroflex.de\/wp-content\/uploads\/2021\/02\/EN388.png 252w, https:\/\/niroflex.de\/wp-content\/uploads\/2021\/02\/EN388-20x18.png 20w\" sizes=\"(max-width: 252px) 100vw, 252px\" \/>[\/vc_toggle][vc_toggle title=\u00bbM\u00e9todo de prueba EN 388:2003&#8243; color=\u00bbjuicy_pink\u00bb size=\u00bblg\u00bb custom_font_container=\u00bbtag:h2|font_size:18|text_align:left|line_height:1&#8243; custom_use_theme_fonts=\u00bbyes\u00bb use_custom_heading=\u00bbtrue\u00bb]\n<p class=\"p1\">La prueba previa de protecci\u00f3n contra cortes para los guantes de protecci\u00f3n contra cortes se lleva a cabo con la ayuda del llamado \u00abCoupe Test\u00bb. Una cuchilla circular giratoria se mueve de un lado a otro sobre el elemento de prueba con una fuerza definida (5N) y gira en la direcci\u00f3n opuesta al movimiento. El filo de la hoja se mide al principio y al final de la prueba utilizando un tejido de referencia. De este modo, se puede determinar el desgaste de la hoja y tenerlo en cuenta en el resultado. El valor del \u00edndice determina los resultados, por un lado, del n\u00famero de ciclos necesarios para cortar la muestra de prueba y, por otro lado, del grado de desgaste de la hoja que hemos utilizado.<\/p>\n[\/vc_toggle][vc_toggle title=\u00bbDIN EN 511 Protecci\u00f3n contra el fr\u00edo\u00bb color=\u00bbjuicy_pink\u00bb size=\u00bblg\u00bb custom_font_container=\u00bbtag:h2|font_size:18|text_align:left|line_height:1%2C5&#8243; custom_use_theme_fonts=\u00bbyes\u00bb use_custom_heading=\u00bbtrue\u00bb]\n<p class=\"p1\">Los guantes certificados seg\u00fan la norma DIN EN 511 est\u00e1n destinados a proteger al usuario tanto del fr\u00edo por convecci\u00f3n (fr\u00edo penetrante) como del fr\u00edo por contacto (contacto directo). Los aspectos individuales se clasifican en diferentes niveles de rendimiento. Los niveles de rendimiento se indican con un n\u00famero del 1 al 4 junto al pictograma, y el 4 describe el nivel de rendimiento m\u00e1s alto.<\/p>\n[\/vc_toggle][vc_toggle title=\u00bbM\u00e9todo de prueba EN 388:2016\/ISO 13997&#8243; color=\u00bbjuicy_pink\u00bb size=\u00bblg\u00bb custom_font_container=\u00bbtag:h2|font_size:18|text_align:left|line_height:1%2C5&#8243; custom_use_theme_fonts=\u00bbyes\u00bb use_custom_heading=\u00bbtrue\u00bb]\n<p class=\"p1\">En el procedimiento de prueba seg\u00fan la ISO 13997, se determina la durabilidad del guante frente a un objeto afilado en un solo contacto bajo una fuerza superior. Para ello, una hoja larga y recta se desplaza una vez sobre la muestra de prueba. La fuerza m\u00ednima a la media del elemento de prueba se determina despu\u00e9s de 20 mil\u00edmetros. El resultado se proporciona en Newton (N) y, seg\u00fan el valor de Newton, la muestra de prueba se clasifica en la clase de protecci\u00f3n contra cortes correspondiente.<\/p>\n[\/vc_toggle][vc_toggle title=\u00bbDIN EN 407 Protecci\u00f3n contra riesgos t\u00e9rmicos\u00bb color=\u00bbjuicy_pink\u00bb size=\u00bblg\u00bb custom_font_container=\u00bbtag:h2|font_size:18|text_align:left|line_height:1%2C5&#8243; custom_use_theme_fonts=\u00bbyes\u00bb use_custom_heading=\u00bbtrue\u00bb]\n<p class=\"p1\">Los guantes de protecci\u00f3n certificados seg\u00fan la norma DIN EN 407 protegen al usuario<span class=\"s1\">,<\/span> por ejemplo<span class=\"s1\">,<\/span> del contacto y del calor radiante. Los guantes de protecci\u00f3n se clasifican y prueban seg\u00fan los siguientes criterios: Protecci\u00f3n contra la ignici\u00f3n &#8211; Protecci\u00f3n contra el calor por contacto &#8211; Protecci\u00f3n contra el calor por convecci\u00f3n.<\/p>\n[\/vc_toggle][\/vc_column][\/vc_row][vc_row thb_divider_position=\u00bbbottom\u00bb][vc_column][vc_empty_space height=\u00bb50px\u00bb][vc_column_text css=\u00bb\u00bb]Se vi havas pliajn demandojn pri niaj produktoj, aplikoj a\u016d sekurecaj normoj, nia serva teamo \u0109iam pretas helpi vin. \u0108u vi bezonas teknikajn detalojn, individuajn solvojn a\u016d konsilojn pri la elekto de la \u011dusta produkto, ni helpos vin rapide kaj fidinde.[\/vc_column_text][vc_empty_space height=\u00bb50px\u00bb]\t<a class=\"btn    animation top-to-bottom  large\" href=\"https:\/\/niroflex.de\/es\/ontacto-niroflex\/\" target=\"_self\" role=\"button\" title=\"P\u00f3ngase en contacto con nosotros\"><span>P\u00f3ngase en contacto con nosotros<\/span><\/a>\n\n\t[vc_empty_space height=\u00bb50px\u00bb][\/vc_column][\/vc_row][vc_row thb_divider_position=\u00bbbottom\u00bb][vc_column][\/vc_column][\/vc_row]\n<\/div>","protected":false},"excerpt":{"rendered":"<p>[vc_row thb_full_width=\u00bbtrue\u00bb parallax=\u00bbcontent-moving\u00bb thb_divider_position=\u00bbbottom\u00bb css=\u00bb.vc_custom_1556805173564{background-color: #000000 !important;background-position: center;background-repeat: no-repeat;background-size:contain !important;}\u00bb][vc_column][vc_empty_space height=\u00bb110px\u00bb][\/vc_column][\/vc_row][vc_row thb_divider_position=\u00bbbottom\u00bb][vc_column][vc_empty_space height=\u00bb80px\u00bb][vc_icon type=\u00bbtypicons\u00bb icon_typicons=\u00bbtypcn typcn-messages\u00bb color=\u00bbcustom\u00bb size=\u00bbxl\u00bb css=\u00bb.vc_custom_1614164153090{padding-bottom: -20px !important;}\u00bb custom_color=\u00bb#dd3333&#8243;][vc_column_text css=\u00bb\u00bb] FAQ \u2013 preguntas frecuentes En \u0109i tiu sekcio, vi trovos la plej gravajn informojn pri niaj produktoj, ilia apliko kaj prizorgado. La Oftaj Demandoj helpos vin rapide trovi respondojn al la plej&hellip;<\/p>\n","protected":false},"author":2,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-9444","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.9 (Yoast SEO v27.9) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>niroflex FAQ | Preguntas frecuentes y respuestas<\/title>\n<meta name=\"description\" content=\"Consulta las respuestas sobre productos niroflex: ropa protectora, guantes y equipos de seguridad. Todas las FAQ resumidas aqu\u00ed.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/niroflex.de\/es\/es-niroflex-faq\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"FAQ \u2013 Preguntas y Respuestas\" \/>\n<meta property=\"og:description\" content=\"FAQ \u2013 preguntas frecuentes En \u0109i tiu sekcio, vi trovos la plej gravajn informojn pri niaj produktoj, ilia apliko kaj prizorgado. La Oftaj Demandoj helpos\" \/>\n<meta property=\"og:url\" content=\"https:\/\/niroflex.de\/es\/es-niroflex-faq\/\" \/>\n<meta property=\"og:site_name\" content=\"Niroflex | Schnittschutzhandschuhe &amp; Kettenhandschuh\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/people\/Friedrich-Mnch-GmbH-Co-KG\/100054195774984\/\" \/>\n<meta property=\"article:modified_time\" content=\"2025-11-19T16:19:41+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/niroflex.de\/wp-content\/uploads\/2021\/02\/LCR_es.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"187\" \/>\n\t<meta property=\"og:image:height\" content=\"55\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/niroflex.de\\\/es\\\/es-niroflex-faq\\\/\",\"url\":\"https:\\\/\\\/niroflex.de\\\/es\\\/es-niroflex-faq\\\/\",\"name\":\"niroflex FAQ | Preguntas frecuentes y respuestas\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/niroflex.de\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/niroflex.de\\\/es\\\/es-niroflex-faq\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/niroflex.de\\\/es\\\/es-niroflex-faq\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/niroflex.de\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/LCR_es.jpg\",\"datePublished\":\"2021-02-25T14:02:39+00:00\",\"dateModified\":\"2025-11-19T16:19:41+00:00\",\"description\":\"Consulta las respuestas sobre productos niroflex: ropa protectora, guantes y equipos de seguridad. Todas las FAQ resumidas aqu\u00ed.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/niroflex.de\\\/es\\\/es-niroflex-faq\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/niroflex.de\\\/es\\\/es-niroflex-faq\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/niroflex.de\\\/es\\\/es-niroflex-faq\\\/#primaryimage\",\"url\":\"https:\\\/\\\/niroflex.de\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/LCR_es.jpg\",\"contentUrl\":\"https:\\\/\\\/niroflex.de\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/LCR_es.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/niroflex.de\\\/es\\\/es-niroflex-faq\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/niroflex.de\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"FAQ \u2013 Preguntas y Respuestas\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/niroflex.de\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/niroflex.de\\\/es\\\/\",\"name\":\"Niroflex | Schnittschutzhandschuhe & Kettenhandschuh\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/niroflex.de\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/niroflex.de\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/niroflex.de\\\/es\\\/#organization\",\"name\":\"Friedrich M\u00fcnch GmbH + Co KG\",\"url\":\"https:\\\/\\\/niroflex.de\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/niroflex.de\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/niroflex.de\\\/wp-content\\\/uploads\\\/2019\\\/03\\\/Niroflex_Logo_2@.png\",\"contentUrl\":\"https:\\\/\\\/niroflex.de\\\/wp-content\\\/uploads\\\/2019\\\/03\\\/Niroflex_Logo_2@.png\",\"width\":480,\"height\":169,\"caption\":\"Friedrich M\u00fcnch GmbH + Co KG\"},\"image\":{\"@id\":\"https:\\\/\\\/niroflex.de\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/people\\\/Friedrich-Mnch-GmbH-Co-KG\\\/100054195774984\\\/\"],\"email\":\"info@niroflex.de\",\"telephone\":\"+49 7041 9544-0\",\"legalName\":\"Friedrich M\u00fcnch GmbH + Co KG\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"niroflex FAQ | Preguntas frecuentes y respuestas","description":"Consulta las respuestas sobre productos niroflex: ropa protectora, guantes y equipos de seguridad. Todas las FAQ resumidas aqu\u00ed.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/niroflex.de\/es\/es-niroflex-faq\/","og_locale":"es_ES","og_type":"article","og_title":"FAQ \u2013 Preguntas y Respuestas","og_description":"FAQ \u2013 preguntas frecuentes En \u0109i tiu sekcio, vi trovos la plej gravajn informojn pri niaj produktoj, ilia apliko kaj prizorgado. La Oftaj Demandoj helpos","og_url":"https:\/\/niroflex.de\/es\/es-niroflex-faq\/","og_site_name":"Niroflex | Schnittschutzhandschuhe &amp; Kettenhandschuh","article_publisher":"https:\/\/www.facebook.com\/people\/Friedrich-Mnch-GmbH-Co-KG\/100054195774984\/","article_modified_time":"2025-11-19T16:19:41+00:00","og_image":[{"width":187,"height":55,"url":"https:\/\/niroflex.de\/wp-content\/uploads\/2021\/02\/LCR_es.jpg","type":"image\/jpeg"}],"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/niroflex.de\/es\/es-niroflex-faq\/","url":"https:\/\/niroflex.de\/es\/es-niroflex-faq\/","name":"niroflex FAQ | Preguntas frecuentes y respuestas","isPartOf":{"@id":"https:\/\/niroflex.de\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/niroflex.de\/es\/es-niroflex-faq\/#primaryimage"},"image":{"@id":"https:\/\/niroflex.de\/es\/es-niroflex-faq\/#primaryimage"},"thumbnailUrl":"https:\/\/niroflex.de\/wp-content\/uploads\/2021\/02\/LCR_es.jpg","datePublished":"2021-02-25T14:02:39+00:00","dateModified":"2025-11-19T16:19:41+00:00","description":"Consulta las respuestas sobre productos niroflex: ropa protectora, guantes y equipos de seguridad. Todas las FAQ resumidas aqu\u00ed.","breadcrumb":{"@id":"https:\/\/niroflex.de\/es\/es-niroflex-faq\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/niroflex.de\/es\/es-niroflex-faq\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/niroflex.de\/es\/es-niroflex-faq\/#primaryimage","url":"https:\/\/niroflex.de\/wp-content\/uploads\/2021\/02\/LCR_es.jpg","contentUrl":"https:\/\/niroflex.de\/wp-content\/uploads\/2021\/02\/LCR_es.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/niroflex.de\/es\/es-niroflex-faq\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/niroflex.de\/es\/"},{"@type":"ListItem","position":2,"name":"FAQ \u2013 Preguntas y Respuestas"}]},{"@type":"WebSite","@id":"https:\/\/niroflex.de\/es\/#website","url":"https:\/\/niroflex.de\/es\/","name":"Niroflex | Schnittschutzhandschuhe & Kettenhandschuh","description":"","publisher":{"@id":"https:\/\/niroflex.de\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/niroflex.de\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/niroflex.de\/es\/#organization","name":"Friedrich M\u00fcnch GmbH + Co KG","url":"https:\/\/niroflex.de\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/niroflex.de\/es\/#\/schema\/logo\/image\/","url":"https:\/\/niroflex.de\/wp-content\/uploads\/2019\/03\/Niroflex_Logo_2@.png","contentUrl":"https:\/\/niroflex.de\/wp-content\/uploads\/2019\/03\/Niroflex_Logo_2@.png","width":480,"height":169,"caption":"Friedrich M\u00fcnch GmbH + Co KG"},"image":{"@id":"https:\/\/niroflex.de\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/people\/Friedrich-Mnch-GmbH-Co-KG\/100054195774984\/"],"email":"info@niroflex.de","telephone":"+49 7041 9544-0","legalName":"Friedrich M\u00fcnch GmbH + Co KG"}]}},"_links":{"self":[{"href":"https:\/\/niroflex.de\/es\/wp-json\/wp\/v2\/pages\/9444","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/niroflex.de\/es\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/niroflex.de\/es\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/niroflex.de\/es\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/niroflex.de\/es\/wp-json\/wp\/v2\/comments?post=9444"}],"version-history":[{"count":20,"href":"https:\/\/niroflex.de\/es\/wp-json\/wp\/v2\/pages\/9444\/revisions"}],"predecessor-version":[{"id":20265,"href":"https:\/\/niroflex.de\/es\/wp-json\/wp\/v2\/pages\/9444\/revisions\/20265"}],"wp:attachment":[{"href":"https:\/\/niroflex.de\/es\/wp-json\/wp\/v2\/media?parent=9444"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}